{"id":9934,"date":"2020-03-24T00:00:00","date_gmt":"2020-03-23T23:00:00","guid":{"rendered":"https:\/\/diverinvest.es\/informe-semanal-23-de-marzo-del-2020\/"},"modified":"2020-03-24T00:00:00","modified_gmt":"2020-03-23T23:00:00","slug":"informe-semanal-23-de-marzo-del-2020","status":"publish","type":"post","link":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/","title":{"rendered":"23\/03\/2020 Informe Semanal"},"content":{"rendered":"<p>Buenos d\u00edas,<\/p>\n<p>La semana pasada termin\u00f3 con un balance de 336.000 casos de coronavirus y 14.000 muertes por el virus. La subida ha sido muy r\u00e1pida en Europa y en los Estados Unidos, que a pesar de encontrarse en una fase m\u00e1s temprana de la epidemia, han superado los 30.000 casos, gran parte de ellos en New York. En esta situaci\u00f3n tan dif\u00edcil, es necesario resaltar que China no est\u00e1 reportando nuevos casos dom\u00e9sticos estos \u00faltimos d\u00edas.<\/p>\n<p>Ligado al \u00faltimo dato de China en cuanto a el virus, la gran potencia asi\u00e1tica ha reabierto f\u00e1bricas durante la semana. Su \u00edndice de referencia, el Shangai Composite, se ha dejado en torno a un 4,5% esta semana acumulando p\u00e9rdidas en el a\u00f1o no superiores al 13%. Un resultado sorprendente en este contexto de fuerte contracci\u00f3n de la demanda global.<\/p>\n<p>La semana empez\u00f3 con la implementaci\u00f3n de un fuerte est\u00edmulo monetario por parte de la FED, recortando los tipos a un rango entre 0 y 0,25% y anunciando compras adicionales de activos por $700 bn. A pesar de ello, el mercado ha seguido descontando el impacto de la pandemia y parece no haber encontrado a\u00fan un soporte fuerte, situ\u00e1ndose el S&#038;P500 en 2.300 puntos. Mientras tanto, los spreads de bonos se han ampliado significativamente, los high yield y los investment grade.<\/p>\n<p>Por su parte, Europa sigue acumulando importantes p\u00e9rdidas en el a\u00f1o y tambi\u00e9n ha anunciado est\u00edmulos. A los monetarios se han sumado ayudas de UK con pr\u00e9stamos gubernamentales por GBP 330 bn, el 12% de su PIB, ayudas fiscales por parte de Espa\u00f1a e Italia (1,4% de su PIB) y Alemania prepara un pack de rescate para su econom\u00eda de EUR 600 bn y a\u00f1ade EUR 156 bn (4,5% sobre su PIB) como presupuesto de emergencia financiado con deuda.<\/p>\n<p>Los est\u00edmulos est\u00e1n llegando de forma global en un contexto de mucha volatilidad en los mercados, con el foco de atenci\u00f3n puesto en la evoluci\u00f3n del virus. Adem\u00e1s, para esta semana cabe destacar la publicaci\u00f3n del PMI Global, datos de confianza del empresas y del consumidor, y el \u00edndice de peticiones de subsidio por desempleo de USA.<\/p>\n<p>Un abrazo,<br \/>\nDavid Levy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos d\u00edas, La semana pasada termin\u00f3 con un balance de 336.000 casos de coronavirus y 14.000 muertes por el virus. La subida ha sido muy r\u00e1pida en Europa y en los Estados Unidos, que a pesar de encontrarse en una fase m\u00e1s temprana de la epidemia, han superado los 30.000 casos, gran parte de ellos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[87,105],"tags":[],"class_list":["post-9934","post","type-post","status-publish","format-standard","hentry","category-prensa-y-actualidad","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>23\/03\/2020 Informe Semanal - DiverInvest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"23\/03\/2020 Informe Semanal - DiverInvest\" \/>\n<meta property=\"og:description\" content=\"Buenos d\u00edas, La semana pasada termin\u00f3 con un balance de 336.000 casos de coronavirus y 14.000 muertes por el virus. La subida ha sido muy r\u00e1pida en Europa y en los Estados Unidos, que a pesar de encontrarse en una fase m\u00e1s temprana de la epidemia, han superado los 30.000 casos, gran parte de ellos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"DiverInvest\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"websalia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"websalia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/\"},\"author\":{\"name\":\"websalia\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#\\\/schema\\\/person\\\/91003206ff1ab9f694a2285ceb978aa3\"},\"headline\":\"23\\\/03\\\/2020 Informe Semanal\",\"datePublished\":\"2020-03-23T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/\"},\"wordCount\":376,\"commentCount\":0,\"articleSection\":[\"Prensa y Actualidad\",\"Noticias\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/\",\"name\":\"23\\\/03\\\/2020 Informe Semanal - DiverInvest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\"},\"datePublished\":\"2020-03-23T23:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#\\\/schema\\\/person\\\/91003206ff1ab9f694a2285ceb978aa3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/informe-semanal-23-de-marzo-del-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"23\\\/03\\\/2020 Informe Semanal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\",\"name\":\"DiverInvest\",\"description\":\"Corporate Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#\\\/schema\\\/person\\\/91003206ff1ab9f694a2285ceb978aa3\",\"name\":\"websalia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc5095c82364285cf0856d4b5beed3f1824191a8900bf32e522aa42feff35088?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc5095c82364285cf0856d4b5beed3f1824191a8900bf32e522aa42feff35088?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc5095c82364285cf0856d4b5beed3f1824191a8900bf32e522aa42feff35088?s=96&d=mm&r=g\",\"caption\":\"websalia\"},\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/author\\\/websalia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"23\/03\/2020 Informe Semanal - DiverInvest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/","og_locale":"ca_ES","og_type":"article","og_title":"23\/03\/2020 Informe Semanal - DiverInvest","og_description":"Buenos d\u00edas, La semana pasada termin\u00f3 con un balance de 336.000 casos de coronavirus y 14.000 muertes por el virus. La subida ha sido muy r\u00e1pida en Europa y en los Estados Unidos, que a pesar de encontrarse en una fase m\u00e1s temprana de la epidemia, han superado los 30.000 casos, gran parte de ellos [&hellip;]","og_url":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/","og_site_name":"DiverInvest","article_published_time":"2020-03-23T23:00:00+00:00","author":"websalia","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"websalia","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/#article","isPartOf":{"@id":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/"},"author":{"name":"websalia","@id":"https:\/\/diverinvest.es\/ca\/#\/schema\/person\/91003206ff1ab9f694a2285ceb978aa3"},"headline":"23\/03\/2020 Informe Semanal","datePublished":"2020-03-23T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/"},"wordCount":376,"commentCount":0,"articleSection":["Prensa y Actualidad","Noticias"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/","url":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/","name":"23\/03\/2020 Informe Semanal - DiverInvest","isPartOf":{"@id":"https:\/\/diverinvest.es\/ca\/#website"},"datePublished":"2020-03-23T23:00:00+00:00","author":{"@id":"https:\/\/diverinvest.es\/ca\/#\/schema\/person\/91003206ff1ab9f694a2285ceb978aa3"},"breadcrumb":{"@id":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/diverinvest.es\/ca\/informe-semanal-23-de-marzo-del-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diverinvest.es\/ca\/"},{"@type":"ListItem","position":2,"name":"23\/03\/2020 Informe Semanal"}]},{"@type":"WebSite","@id":"https:\/\/diverinvest.es\/ca\/#website","url":"https:\/\/diverinvest.es\/ca\/","name":"DiverInvest","description":"Corporate Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diverinvest.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/diverinvest.es\/ca\/#\/schema\/person\/91003206ff1ab9f694a2285ceb978aa3","name":"websalia","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/fc5095c82364285cf0856d4b5beed3f1824191a8900bf32e522aa42feff35088?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc5095c82364285cf0856d4b5beed3f1824191a8900bf32e522aa42feff35088?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc5095c82364285cf0856d4b5beed3f1824191a8900bf32e522aa42feff35088?s=96&d=mm&r=g","caption":"websalia"},"url":"https:\/\/diverinvest.es\/ca\/author\/websalia\/"}]}},"_links":{"self":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/posts\/9934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/comments?post=9934"}],"version-history":[{"count":0,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/posts\/9934\/revisions"}],"wp:attachment":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media?parent=9934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/categories?post=9934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/tags?post=9934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}