{"id":11540,"date":"2024-12-16T10:19:01","date_gmt":"2024-12-16T09:19:01","guid":{"rendered":"https:\/\/diverinvest.es\/?post_type=cartas-de-david&#038;p=11540"},"modified":"2026-04-22T08:34:58","modified_gmt":"2026-04-22T06:34:58","slug":"carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie","status":"publish","type":"cartas-de-david","link":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/","title":{"rendered":"Carta diciembre 2024: &#8220;Perspectivas 2025: Sigue mientras nada cambie&#8221;"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Estimado amigo,<br>\u00a0<br>Un a\u00f1o m\u00e1s llega el momento de compartiros nuestras previsiones. Como siempre, una oda al mar ya que la realidad, es que nadie sabe lo que va a pasar. Eso es lo bonito de este negocio, tenemos que afrontar un nuevo a\u00f1o donde todos los marcadores se ponen a cero y nos toca volver a demostrar que somos los mejores.<br>\u00a0<br>Entramos en los \u00faltimos d\u00edas de trading del 2024, desafortunadamente ya que est\u00e1 siendo un a\u00f1o excepcional, tanto para la renta fija, como para la renta variable. \u00a0En especial, la bolsa americana, ha vuelto a brillar por encima de todas y el sector tecnol\u00f3gico se ha llevado la palma. \u00a0A\u00f1o bueno tanto para el d\u00f3lar como para el inmobiliario. \u00a0No tanto para el Private Equity que est\u00e1 sufriendo, ya que no se acaban de materializar las operaciones de venta que se esperaban y las de compra cada vez son m\u00e1s exigentes, su entorno no es tan favorable.<br>\u00a0<br>Ahora la gran pregunta es qu\u00e9 pasar\u00e1 en el 2025. Nosotros mantenemos, por el momento, un escenario muy parecido. El mercado ha entrado en una inercia muy fuerte y nada hace pensar que a corto plazo eso vaya a cambiar. M\u00e1s bien todo lo contrario. Nuestras bases de trabajo y tesis de inversi\u00f3n asentadas en estos \u00faltimos dos a\u00f1os se est\u00e1n viendo reforzadas.\u00a0<br>\u00a0<br>La realidad es que la situaci\u00f3n macroecon\u00f3mica mundial es correcta. Se espera un crecimiento del PIB mundial del 3%. Los beneficios estimados para los dos pr\u00f3ximos a\u00f1os de las empresas presentan crecimientos del 14% y del 12% sucesivamente. M\u00e1s que suficiente para seguir adelante. Adem\u00e1s, como hemos podido volver a constatar, la geopol\u00edtica, a pesar de todas las guerras e inestabilidades pol\u00edticas en varios pa\u00edses del mundo, no afecta a los mercados financieros que siguen su curso.<br>\u00a0<br>Mientras nada cambie, con modestia, pensamos que hay que seguir igual. En cuanto a la renta variable, sobreponderar o solo invertir en la bolsa americana, ya dijimos que Europa rien de rien. La renta fija en Europa tampoco ofrece valor, en cambio la renta fija americana es un dulce. El d\u00f3lar seguir\u00e1 fuerte y quiz\u00e1s veamos la paridad este a\u00f1o. Recuerda que el d\u00f3lar ofrece ese jackpot de ser el \u00fanico activo refugio del mundo. El inmobiliario y el Private Equity se enfrentan a un entorno muy competitivo, no solo entre su propio sector, sino tambi\u00e9n ante los otros activos financieros ya que las expectativas de rentabilidad se han equilibrado y ya nos son esa alternativa de inversi\u00f3n rentable y atractiva frente al resto de activos. S\u00f3lo quiero destacar que para invertir en dichos activos recomendamos abordarlos con gestores expertos.<br>\u00a0<br>Nuestro consejo sigue siendo no hacer inventos, ni querer ser m\u00e1s listos que la media. Se disciplinado y no te dejes llevar por la tentaci\u00f3n, recuerda que la rentabilidad nunca es a cambio de nada. Los excesos ya sabemos que no son buenos y todos conocemos c\u00f3mo acaban. Esta vez, nuestra visi\u00f3n coincide con la mayor\u00eda de las entidades, que tambi\u00e9n tienen una visi\u00f3n positiva para este pr\u00f3ximo a\u00f1o.<br>\u00a0<br>Nuestra recomendaci\u00f3n es: sigue adelante mientras nada cambie. Y recuerda, la mejor inversi\u00f3n es la vida.<br>\u00a0<br>Felices inversiones 2025,<br>David Levy<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Estimado amigo,\u00a0Un a\u00f1o m\u00e1s llega el momento de compartiros nuestras previsiones. Como siempre, una oda al mar ya que la realidad, es que nadie sabe lo que va a pasar. Eso es lo bonito de este negocio, tenemos que afrontar un nuevo a\u00f1o donde todos los marcadores se ponen a cero y nos toca volver [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":11541,"parent":0,"template":"","categories":[529],"class_list":["post-11540","cartas-de-david","type-cartas-de-david","status-publish","has-post-thumbnail","hentry","category-cartas-2024-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta diciembre 2024: &quot;Perspectivas 2025: Sigue mientras nada cambie&quot; - DiverInvest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta diciembre 2024: &quot;Perspectivas 2025: Sigue mientras nada cambie&quot; - DiverInvest\" \/>\n<meta property=\"og:description\" content=\"Estimado amigo,\u00a0Un a\u00f1o m\u00e1s llega el momento de compartiros nuestras previsiones. Como siempre, una oda al mar ya que la realidad, es que nadie sabe lo que va a pasar. Eso es lo bonito de este negocio, tenemos que afrontar un nuevo a\u00f1o donde todos los marcadores se ponen a cero y nos toca volver [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/\" \/>\n<meta property=\"og:site_name\" content=\"DiverInvest\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T06:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diverinvest.es\/wp-content\/uploads\/cuadro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"587\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\\\/\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\\\/\",\"name\":\"Carta diciembre 2024: \\\"Perspectivas 2025: Sigue mientras nada cambie\\\" - DiverInvest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/cuadro.jpg\",\"datePublished\":\"2024-12-16T09:19:01+00:00\",\"dateModified\":\"2026-04-22T06:34:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/cuadro.jpg\",\"contentUrl\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/cuadro.jpg\",\"width\":587,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartas de David\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carta diciembre 2024: &#8220;Perspectivas 2025: Sigue mientras nada cambie&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\",\"name\":\"DiverInvest\",\"description\":\"Corporate Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta diciembre 2024: \"Perspectivas 2025: Sigue mientras nada cambie\" - DiverInvest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/","og_locale":"ca_ES","og_type":"article","og_title":"Carta diciembre 2024: \"Perspectivas 2025: Sigue mientras nada cambie\" - DiverInvest","og_description":"Estimado amigo,\u00a0Un a\u00f1o m\u00e1s llega el momento de compartiros nuestras previsiones. Como siempre, una oda al mar ya que la realidad, es que nadie sabe lo que va a pasar. Eso es lo bonito de este negocio, tenemos que afrontar un nuevo a\u00f1o donde todos los marcadores se ponen a cero y nos toca volver [&hellip;]","og_url":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/","og_site_name":"DiverInvest","article_modified_time":"2026-04-22T06:34:58+00:00","og_image":[{"width":587,"height":377,"url":"https:\/\/diverinvest.es\/wp-content\/uploads\/cuadro.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/","url":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/","name":"Carta diciembre 2024: \"Perspectivas 2025: Sigue mientras nada cambie\" - DiverInvest","isPartOf":{"@id":"https:\/\/diverinvest.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/#primaryimage"},"image":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/#primaryimage"},"thumbnailUrl":"https:\/\/diverinvest.es\/wp-content\/uploads\/cuadro.jpg","datePublished":"2024-12-16T09:19:01+00:00","dateModified":"2026-04-22T06:34:58+00:00","breadcrumb":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/#primaryimage","url":"https:\/\/diverinvest.es\/wp-content\/uploads\/cuadro.jpg","contentUrl":"https:\/\/diverinvest.es\/wp-content\/uploads\/cuadro.jpg","width":587,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-diciembre-2024-perspectivas-2025-sigue-mientras-nada-cambie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diverinvest.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Cartas de David","item":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/"},{"@type":"ListItem","position":3,"name":"Carta diciembre 2024: &#8220;Perspectivas 2025: Sigue mientras nada cambie&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/diverinvest.es\/ca\/#website","url":"https:\/\/diverinvest.es\/ca\/","name":"DiverInvest","description":"Corporate Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diverinvest.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/cartas-de-david\/11540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/cartas-de-david"}],"about":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/types\/cartas-de-david"}],"author":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/users\/10"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media\/11541"}],"wp:attachment":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media?parent=11540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/categories?post=11540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}