{"id":11181,"date":"2024-02-04T11:47:28","date_gmt":"2024-02-04T10:47:28","guid":{"rendered":"https:\/\/diverinvest.es\/?post_type=cartas-de-david&#038;p=11181"},"modified":"2026-04-22T08:45:08","modified_gmt":"2026-04-22T06:45:08","slug":"febrero-2024-riesgo-de-reinversion-en-renta-fija","status":"publish","type":"cartas-de-david","link":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/","title":{"rendered":"Febrero 2024: &#8220;Riesgo de reinversi\u00f3n en renta fija&#8221;"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Estimado amigo,\u00a0<br> \u00a0 <br>Como bien sabes, los tipos de inter\u00e9s han sufrido una de las subidas m\u00e1s pronunciadas y r\u00e1pidas de la historia en los \u00faltimos 9 meses. Os recuerdo que hemos pasado de tipos de inter\u00e9s negativos a corto plazo a tipos del 4%, una locura. Un nivel de tipos que pens\u00e1bamos que jam\u00e1s \u00edbamos a volver a vivir, o al menos un servidor.\u00a0 <br>\u00a0<br>Hoy muchos piensan que los tipos a corto seguir\u00e1n altos por mucho tiempo. Adem\u00e1s, al estar la curva de tipos invertida, el corto paga m\u00e1s que el largo, la mayor\u00eda de los inversores no quieren mirar m\u00e1s all\u00e1.\u00a0 \u00a0<br><br>La econom\u00eda es din\u00e1mica y est\u00e1 funcionando mejor de lo que pens\u00e1bamos, las perspectivas son buenas y la l\u00f3gica invita a pensar que los tipos de corto volver\u00e1n a bajar. Como siempre, nadie sabe cu\u00e1ndo ni cu\u00e1nto.\u00a0 \u00a0<br><br>Por lo tanto, si nos centramos en la renta fija a corto plazo, me refiero a cuenta corriente, dep\u00f3sitos y emisiones de renta fija hasta m\u00e1ximo 2 a\u00f1os de vencimiento, se nos presenta una reflexi\u00f3n importante.\u00a0 \u00a0<br><br>Aquellos inversores que opten por no hacer nada y decidan por quedarse en la parte corta de la curva se van a enfrentar a un alto riesgo de reinversi\u00f3n: \u00bfA qu\u00e9 tipo vas a poder renovar tu inversi\u00f3n de corto plazo dentro de unos meses?\u00a0 Este hecho nos preocupa en exceso y recomendamos tomar parte activa en esta aparentemente simple decisi\u00f3n de inversi\u00f3n.\u00a0<br>\u00a0<br>La pregunta es \u00bfQu\u00e9 podemos o debemos hacer?\u00a0 Nuestra recomendaci\u00f3n es buscar un carry atractivo y asegurarlo cuanto m\u00e1s tiempo mejor. El riesgo de reinversi\u00f3n en un futuro pr\u00f3ximo nos parece demasiado alto. La renta fija no es fija y vuelve a ser un activo altamente rentable.\u00a0 \u00a0 Hoy puedes adelantar el trabajo y asegurar un rendimiento atractivo de una parte significativa de tu patrimonio, y para muchos a\u00f1os. \u00a1A que esperas!\u00a0 \u00a0 <br><br>Un abrazo,\u00a0\u00a0<br>David Levy \u00a0<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Estimado amigo,\u00a0 \u00a0 Como bien sabes, los tipos de inter\u00e9s han sufrido una de las subidas m\u00e1s pronunciadas y r\u00e1pidas de la historia en los \u00faltimos 9 meses. Os recuerdo que hemos pasado de tipos de inter\u00e9s negativos a corto plazo a tipos del 4%, una locura. Un nivel de tipos que pens\u00e1bamos que jam\u00e1s [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":11182,"parent":0,"template":"","categories":[529],"class_list":["post-11181","cartas-de-david","type-cartas-de-david","status-publish","has-post-thumbnail","hentry","category-cartas-2024-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Febrero 2024: &quot;Riesgo de reinversi\u00f3n en renta fija&quot; - DiverInvest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Febrero 2024: &quot;Riesgo de reinversi\u00f3n en renta fija&quot; - DiverInvest\" \/>\n<meta property=\"og:description\" content=\"Estimado amigo,\u00a0 \u00a0 Como bien sabes, los tipos de inter\u00e9s han sufrido una de las subidas m\u00e1s pronunciadas y r\u00e1pidas de la historia en los \u00faltimos 9 meses. Os recuerdo que hemos pasado de tipos de inter\u00e9s negativos a corto plazo a tipos del 4%, una locura. Un nivel de tipos que pens\u00e1bamos que jam\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/\" \/>\n<meta property=\"og:site_name\" content=\"DiverInvest\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T06:45:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-febrero-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1134\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/febrero-2024-riesgo-de-reinversion-en-renta-fija\\\/\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/febrero-2024-riesgo-de-reinversion-en-renta-fija\\\/\",\"name\":\"Febrero 2024: \\\"Riesgo de reinversi\u00f3n en renta fija\\\" - DiverInvest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/febrero-2024-riesgo-de-reinversion-en-renta-fija\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/febrero-2024-riesgo-de-reinversion-en-renta-fija\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-carta-febrero-24.jpg\",\"datePublished\":\"2024-02-04T10:47:28+00:00\",\"dateModified\":\"2026-04-22T06:45:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/febrero-2024-riesgo-de-reinversion-en-renta-fija\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/febrero-2024-riesgo-de-reinversion-en-renta-fija\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/febrero-2024-riesgo-de-reinversion-en-renta-fija\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-carta-febrero-24.jpg\",\"contentUrl\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-carta-febrero-24.jpg\",\"width\":1134,\"height\":1417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/febrero-2024-riesgo-de-reinversion-en-renta-fija\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartas de David\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Febrero 2024: &#8220;Riesgo de reinversi\u00f3n en renta fija&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\",\"name\":\"DiverInvest\",\"description\":\"Corporate Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Febrero 2024: \"Riesgo de reinversi\u00f3n en renta fija\" - DiverInvest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/","og_locale":"ca_ES","og_type":"article","og_title":"Febrero 2024: \"Riesgo de reinversi\u00f3n en renta fija\" - DiverInvest","og_description":"Estimado amigo,\u00a0 \u00a0 Como bien sabes, los tipos de inter\u00e9s han sufrido una de las subidas m\u00e1s pronunciadas y r\u00e1pidas de la historia en los \u00faltimos 9 meses. Os recuerdo que hemos pasado de tipos de inter\u00e9s negativos a corto plazo a tipos del 4%, una locura. Un nivel de tipos que pens\u00e1bamos que jam\u00e1s [&hellip;]","og_url":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/","og_site_name":"DiverInvest","article_modified_time":"2026-04-22T06:45:08+00:00","og_image":[{"width":1134,"height":1417,"url":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-febrero-24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/","url":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/","name":"Febrero 2024: \"Riesgo de reinversi\u00f3n en renta fija\" - DiverInvest","isPartOf":{"@id":"https:\/\/diverinvest.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/#primaryimage"},"image":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/#primaryimage"},"thumbnailUrl":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-febrero-24.jpg","datePublished":"2024-02-04T10:47:28+00:00","dateModified":"2026-04-22T06:45:08+00:00","breadcrumb":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/#primaryimage","url":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-febrero-24.jpg","contentUrl":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-febrero-24.jpg","width":1134,"height":1417},{"@type":"BreadcrumbList","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/febrero-2024-riesgo-de-reinversion-en-renta-fija\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diverinvest.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Cartas de David","item":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/"},{"@type":"ListItem","position":3,"name":"Febrero 2024: &#8220;Riesgo de reinversi\u00f3n en renta fija&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/diverinvest.es\/ca\/#website","url":"https:\/\/diverinvest.es\/ca\/","name":"DiverInvest","description":"Corporate Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diverinvest.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/cartas-de-david\/11181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/cartas-de-david"}],"about":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/types\/cartas-de-david"}],"author":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/users\/10"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media\/11182"}],"wp:attachment":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media?parent=11181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/categories?post=11181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}