{"id":10169,"date":"2023-10-27T08:01:04","date_gmt":"2023-10-27T06:01:04","guid":{"rendered":"https:\/\/diverinvest.es\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/"},"modified":"2024-01-18T13:01:31","modified_gmt":"2024-01-18T12:01:31","slug":"octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico","status":"publish","type":"cartas-de-david","link":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/","title":{"rendered":"Octubre 2023: &#8220;El poder del inter\u00e9s compuesto en un momento hist\u00f3rico&#8221;"},"content":{"rendered":"\n<p>Estimado\u00a0amigo,<br><br>En la d\u00e9cada de los 80 los tipos de inter\u00e9s rondaban el 15%. Durante los \u00faltimos 10 a\u00f1os, los tipos han estado al 1% y llegando, en su fase final, a pagar por tener dinero. Nosotros, siempre hemos defendido que estas fases, son momentos an\u00f3malos que no deben ser considerados dentro del an\u00e1lisis de la renta fija a largo plazo.<br><br>La realidad es que tenemos historia de tipos desde hace m\u00e1s de 200 a\u00f1os, y las emisiones en aquellas \u00e9pocas ya rondaban el 4% de rentabilidad. Por lo tanto, podemos afirmar con seguridad que las tasas actuales son buenas inversiones a largo plazo.<br><br>El problema es que los inversores como el mercado se centran exclusivamente en el componente del precio para juzgar si, a corto plazo, la decisi\u00f3n de compra de un bono es buena o mala. \u00a0Pero este an\u00e1lisis es deficiente debido a que el perfil de rendimiento de un bono no es lineal sino exponencial.<br><br>En un bono, el precio final y los cupones son fijos y conocidos pero el tercer componente que contribuye al rendimiento, la reinversi\u00f3n de los cupones es variable y depende del vencimiento y del nivel de reinversi\u00f3n durante la vida del bono.<br><br>Como ejemplos explicativos, para un bono a diez a\u00f1os con un cup\u00f3n del 5% y suponiendo que reinvertimos a esa misma tasa inicial, el componente de reinversi\u00f3n supone el 13% del rendimiento total. Para un bono a veinte a\u00f1os, este porcentaje es casi del 50%, y para un bono a treinta a\u00f1os el porcentaje es de m\u00e1s del 70%.<br><br>El poder del inter\u00e9s compuesto todav\u00eda es m\u00e1s potente y atractivo si durante la vida del bono los tipos de inter\u00e9s suben, es decir el precio es inferior al precio de compra inicial, nuestro rendimiento final ser\u00e1 superior porque el componente de reinversi\u00f3n aumenta.<br><br>Quiero mencionar que para este tipo de activo el producto final, el banco o la fiscalidad, son hechos cruciales para la buena implementaci\u00f3n de dicha estrategia.<br><br>Hace un a\u00f1o, con los tipos en negativo, ning\u00fan analista ni gur\u00fa o visionario, predijo ni se imaginaba donde estar\u00edamos hoy, con tasas tan altas y de forma tan r\u00e1pida. Hoy podemos afirmar que ciertos activos de renta fija est\u00e1n ante un momento hist\u00f3rico de compra para aquellos inversores que como t\u00fa ahora s\u00ed entienden lo que es y c\u00f3mo funciona un bono.<br><br>A nivel conceptual, siempre hemos defendido que, si compras activos de calidad a buen precio, eso siempre va a tener valor. Nos da igual lo que vaya a pasar de forma objetiva en los pr\u00f3ximos a\u00f1os.<br><br>Por lo tanto, sin saber lo que va a ocurrir en los pr\u00f3ximos meses o a\u00f1os, ya sab\u00e9is que mi bola de cristal a veces me falla, nuestra recomendaci\u00f3n es simple, compra bonos y reinvierte sus cupones de forma sistem\u00e1tica.<br><br>Que no se te pase el arroz, ahora que todo el mundo predice que los tipos van a seguir subiendo y se van a quedar altos mucho tiempo\u2026<br><br>Un abrazo,<br>David Levy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimado\u00a0amigo, En la d\u00e9cada de los 80 los tipos de inter\u00e9s rondaban el 15%. Durante los \u00faltimos 10 a\u00f1os, los tipos han estado al 1% y llegando, en su fase final, a pagar por tener dinero. Nosotros, siempre hemos defendido que estas fases, son momentos an\u00f3malos que no deben ser considerados dentro del an\u00e1lisis de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6846,"parent":0,"template":"","categories":[165,166,167,168,169,170,171,172,173,174,175,176,177,178],"class_list":["post-10169","cartas-de-david","type-cartas-de-david","status-publish","has-post-thumbnail","hentry","category-carta-2008","category-cartas-2009","category-cartas-2010","category-cartas-2011","category-cartas-2012","category-cartas-2013","category-cartas-2014","category-cartas-2015","category-cartas-2016","category-cartas-2017","category-cartas-2018","category-carta-2020","category-cartas-2019","category-cartas-2021"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Octubre 2023: &quot;El poder del inter\u00e9s compuesto en un momento hist\u00f3rico&quot; - DiverInvest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Octubre 2023: &quot;El poder del inter\u00e9s compuesto en un momento hist\u00f3rico&quot; - DiverInvest\" \/>\n<meta property=\"og:description\" content=\"Estimado\u00a0amigo, En la d\u00e9cada de los 80 los tipos de inter\u00e9s rondaban el 15%. Durante los \u00faltimos 10 a\u00f1os, los tipos han estado al 1% y llegando, en su fase final, a pagar por tener dinero. Nosotros, siempre hemos defendido que estas fases, son momentos an\u00f3malos que no deben ser considerados dentro del an\u00e1lisis de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/\" \/>\n<meta property=\"og:site_name\" content=\"DiverInvest\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-18T12:01:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-OCTUBRE-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1134\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\\\/\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\\\/\",\"name\":\"Octubre 2023: \\\"El poder del inter\u00e9s compuesto en un momento hist\u00f3rico\\\" - DiverInvest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-carta-OCTUBRE-4.jpg\",\"datePublished\":\"2023-10-27T06:01:04+00:00\",\"dateModified\":\"2024-01-18T12:01:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-carta-OCTUBRE-4.jpg\",\"contentUrl\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-carta-OCTUBRE-4.jpg\",\"width\":1134,\"height\":1417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartas de David\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Octubre 2023: &#8220;El poder del inter\u00e9s compuesto en un momento hist\u00f3rico&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\",\"name\":\"DiverInvest\",\"description\":\"Corporate Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Octubre 2023: \"El poder del inter\u00e9s compuesto en un momento hist\u00f3rico\" - DiverInvest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/","og_locale":"ca_ES","og_type":"article","og_title":"Octubre 2023: \"El poder del inter\u00e9s compuesto en un momento hist\u00f3rico\" - DiverInvest","og_description":"Estimado\u00a0amigo, En la d\u00e9cada de los 80 los tipos de inter\u00e9s rondaban el 15%. Durante los \u00faltimos 10 a\u00f1os, los tipos han estado al 1% y llegando, en su fase final, a pagar por tener dinero. Nosotros, siempre hemos defendido que estas fases, son momentos an\u00f3malos que no deben ser considerados dentro del an\u00e1lisis de [&hellip;]","og_url":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/","og_site_name":"DiverInvest","article_modified_time":"2024-01-18T12:01:31+00:00","og_image":[{"width":1134,"height":1417,"url":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-OCTUBRE-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/","url":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/","name":"Octubre 2023: \"El poder del inter\u00e9s compuesto en un momento hist\u00f3rico\" - DiverInvest","isPartOf":{"@id":"https:\/\/diverinvest.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/#primaryimage"},"image":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/#primaryimage"},"thumbnailUrl":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-OCTUBRE-4.jpg","datePublished":"2023-10-27T06:01:04+00:00","dateModified":"2024-01-18T12:01:31+00:00","breadcrumb":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/#primaryimage","url":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-OCTUBRE-4.jpg","contentUrl":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-carta-OCTUBRE-4.jpg","width":1134,"height":1417},{"@type":"BreadcrumbList","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/octubre-2023-el-poder-del-interes-compuesto-en-un-momento-historico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diverinvest.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Cartas de David","item":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/"},{"@type":"ListItem","position":3,"name":"Octubre 2023: &#8220;El poder del inter\u00e9s compuesto en un momento hist\u00f3rico&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/diverinvest.es\/ca\/#website","url":"https:\/\/diverinvest.es\/ca\/","name":"DiverInvest","description":"Corporate Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diverinvest.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/cartas-de-david\/10169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/cartas-de-david"}],"about":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/types\/cartas-de-david"}],"author":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media\/6846"}],"wp:attachment":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media?parent=10169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/categories?post=10169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}