{"id":10155,"date":"2022-11-26T11:41:54","date_gmt":"2022-11-26T10:41:54","guid":{"rendered":"https:\/\/diverinvest.es\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/"},"modified":"2024-03-14T12:27:11","modified_gmt":"2024-03-14T11:27:11","slug":"carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades","status":"publish","type":"cartas-de-david","link":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/","title":{"rendered":"Carta Noviembre 2022: &#8220;La renta fija, un buen regalo para estas navidades&#8221;"},"content":{"rendered":"\n<p>Estimado\u00a0amigo,<br><br>Como sabes este 2022 va por el camino de ser el segundo peor a\u00f1o, en t\u00e9rminos de rentabilidades, tras el crack del 29 para cualquier perfil de inversor, tanto los conservadores como los arriesgados. Las malas rentabilidades de los activos de renta variable han venido acompa\u00f1adas por fuertes ca\u00eddas de los activos de renta fija. Quiz\u00e1s sus bajadas no salen en las noticias, pero este a\u00f1o son devastadoras. Ca\u00eddas jam\u00e1s vistas en 200 a\u00f1os. Sobre todo, en bonos de gobierno o bonos corporativos.<br><br>Me gustar\u00eda centrarme \u00fanicamente en el mercado de renta fija ya que ha estado fuera del radar de los inversores durante varios a\u00f1os por sus bajos niveles de rentabilidad. Ahora vuelve a ser un activo altamente interesante y empieza a competir seriamente con la renta variable y sobre todo con los activos inmobiliarios.<br><br>En DiverInvest, creemos firmemente que la renta fija debe volver a convertirse en un activo estrat\u00e9gico de medio plazo en las carteras de inversi\u00f3n de los clientes. Parece que los tipos altos han venido para quedarse y eso es una gran noticia.<br><br>Todo indica que los bancos centrales ya no quieren fomentar una econom\u00eda forjada con tipos bajos nunca m\u00e1s. La tendencia bajista de tipos que viene de casi 30 a\u00f1os se ha acabado. Y lo que es mejor, los tipos moderadamente altos y con algo de inflaci\u00f3n deber\u00eda volver a ser la norma.<br><br>La realidad es que, en medio de la tempestad, es cuando aparecen casi siempre las buenas oportunidades para los inversores. Ahora hemos de trabajar para encontrar el nivel \u00f3ptimo de tipos de inter\u00e9s ante la situaci\u00f3n econ\u00f3mica actual.<br><br>En Estados Unidos las subidas de tipos ya han sido muy fuertes y lo peor ya deber\u00eda haber pasado. Todo parece indicar que acabara en el rango del 3.00% al 4.00% en plazos largos, la media de los \u00faltimos 200 a\u00f1os. Y como siempre, el objetivo es intentar optimizar los mejores niveles de entrada en un mercado altamente vol\u00e1til. Pero si, como decimos, pensamos que al final los tipos converger\u00e1n en ese rango 3-4%, estamos ante una oportunidad \u00fanica de compra de bonos a largo plazo.<br><br>En Europa la cosa es muy distinta, aunque tambi\u00e9n se han puesto las pilas. El Banco Central Europeo parece convencido de ejecutar este proceso, lo est\u00e1n haciendo con m\u00e1s retraso y menos fuerza, pero con el mismo objetivo. Hoy parece que ya estamos llegando a la mitad del periodo de subidas. Este ciclo podr\u00eda finalizar a finales del 2023, valga la redundancia y estabilizarse sobre niveles del 3.00%.<br><br>Ante este escenario, \u00bfa qu\u00e9 esperas? Escribe tu carta a Pap\u00e1 Noel y construye una buena cartera de bonos para los pr\u00f3ximos a\u00f1os. Hoy, encontrar papeles de deuda de buena calidad al 4%, 5% y 6% es una realidad y es el mejor regalo que le puedes hacer a tus inversiones.<br><br><br>Un abrazo fuerte,<br><br>David Levy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimado\u00a0amigo, Como sabes este 2022 va por el camino de ser el segundo peor a\u00f1o, en t\u00e9rminos de rentabilidades, tras el crack del 29 para cualquier perfil de inversor, tanto los conservadores como los arriesgados. Las malas rentabilidades de los activos de renta variable han venido acompa\u00f1adas por fuertes ca\u00eddas de los activos de renta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6792,"parent":0,"template":"","categories":[165,166,167,168,169,170,171,172,173,174,175,176,177,178],"class_list":["post-10155","cartas-de-david","type-cartas-de-david","status-publish","has-post-thumbnail","hentry","category-carta-2008","category-cartas-2009","category-cartas-2010","category-cartas-2011","category-cartas-2012","category-cartas-2013","category-cartas-2014","category-cartas-2015","category-cartas-2016","category-cartas-2017","category-cartas-2018","category-carta-2020","category-cartas-2019","category-cartas-2021"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta Noviembre 2022: &quot;La renta fija, un buen regalo para estas navidades&quot; - DiverInvest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Noviembre 2022: &quot;La renta fija, un buen regalo para estas navidades&quot; - DiverInvest\" \/>\n<meta property=\"og:description\" content=\"Estimado\u00a0amigo, Como sabes este 2022 va por el camino de ser el segundo peor a\u00f1o, en t\u00e9rminos de rentabilidades, tras el crack del 29 para cualquier perfil de inversor, tanto los conservadores como los arriesgados. Las malas rentabilidades de los activos de renta variable han venido acompa\u00f1adas por fuertes ca\u00eddas de los activos de renta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/\" \/>\n<meta property=\"og:site_name\" content=\"DiverInvest\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T11:27:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-noviembre-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1134\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\\\/\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\\\/\",\"name\":\"Carta Noviembre 2022: \\\"La renta fija, un buen regalo para estas navidades\\\" - DiverInvest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-noviembre-4.jpg\",\"datePublished\":\"2022-11-26T10:41:54+00:00\",\"dateModified\":\"2024-03-14T11:27:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-noviembre-4.jpg\",\"contentUrl\":\"https:\\\/\\\/diverinvest.es\\\/wp-content\\\/uploads\\\/foto-noviembre-4.jpg\",\"width\":1134,\"height\":1417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartas de David\",\"item\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/cartas-de-david\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carta Noviembre 2022: &#8220;La renta fija, un buen regalo para estas navidades&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/\",\"name\":\"DiverInvest\",\"description\":\"Corporate Family Office\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diverinvest.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Noviembre 2022: \"La renta fija, un buen regalo para estas navidades\" - DiverInvest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/","og_locale":"ca_ES","og_type":"article","og_title":"Carta Noviembre 2022: \"La renta fija, un buen regalo para estas navidades\" - DiverInvest","og_description":"Estimado\u00a0amigo, Como sabes este 2022 va por el camino de ser el segundo peor a\u00f1o, en t\u00e9rminos de rentabilidades, tras el crack del 29 para cualquier perfil de inversor, tanto los conservadores como los arriesgados. Las malas rentabilidades de los activos de renta variable han venido acompa\u00f1adas por fuertes ca\u00eddas de los activos de renta [&hellip;]","og_url":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/","og_site_name":"DiverInvest","article_modified_time":"2024-03-14T11:27:11+00:00","og_image":[{"width":1134,"height":1417,"url":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-noviembre-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/","url":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/","name":"Carta Noviembre 2022: \"La renta fija, un buen regalo para estas navidades\" - DiverInvest","isPartOf":{"@id":"https:\/\/diverinvest.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/#primaryimage"},"image":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/#primaryimage"},"thumbnailUrl":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-noviembre-4.jpg","datePublished":"2022-11-26T10:41:54+00:00","dateModified":"2024-03-14T11:27:11+00:00","breadcrumb":{"@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/#primaryimage","url":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-noviembre-4.jpg","contentUrl":"https:\/\/diverinvest.es\/wp-content\/uploads\/foto-noviembre-4.jpg","width":1134,"height":1417},{"@type":"BreadcrumbList","@id":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/carta-noviembre-2022-la-renta-fija-un-buen-regalo-para-estas-navidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diverinvest.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Cartas de David","item":"https:\/\/diverinvest.es\/ca\/cartas-de-david\/"},{"@type":"ListItem","position":3,"name":"Carta Noviembre 2022: &#8220;La renta fija, un buen regalo para estas navidades&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/diverinvest.es\/ca\/#website","url":"https:\/\/diverinvest.es\/ca\/","name":"DiverInvest","description":"Corporate Family Office","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diverinvest.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/cartas-de-david\/10155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/cartas-de-david"}],"about":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/types\/cartas-de-david"}],"author":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media\/6792"}],"wp:attachment":[{"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/media?parent=10155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diverinvest.es\/ca\/wp-json\/wp\/v2\/categories?post=10155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}